{"id":60,"date":"2024-03-11T16:33:55","date_gmt":"2024-03-11T19:33:55","guid":{"rendered":"https:\/\/graduacao.uel.br\/educacao-fisica\/?page_id=60"},"modified":"2024-03-11T16:34:10","modified_gmt":"2024-03-11T19:34:10","slug":"formularios","status":"publish","type":"page","link":"https:\/\/graduacao.uel.br\/educacao-fisica\/formularios\/","title":{"rendered":"Formul\u00e1rios"},"content":{"rendered":"\n<p><a href=\"https:\/\/sites.uel.br\/prograd\/estudante\/formularios\/\"><strong>Formul\u00e1rios<\/strong><\/a>\u00a0e<strong>\u00a0<a href=\"https:\/\/sites.uel.br\/prograd\/documentos\/\">Documentos<\/a><\/strong>\u00a0referentes ao estudante de gradua\u00e7\u00e3o da UEL, encontram-se na sua totalidade no site da Pr\u00f3 Reitoria de Gradua\u00e7\u00e3o (PROGRAD) e espec\u00edficos no Portal do Estudante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formul\u00e1rios\u00a0e\u00a0Documentos\u00a0referentes ao estudante de gradua\u00e7\u00e3o da UEL, encontram-se na sua totalidade no site da Pr\u00f3 Reitoria de Gradua\u00e7\u00e3o (PROGRAD) e espec\u00edficos no Portal do Estudante.<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/pages\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":2,"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"predecessor-version":[{"id":62,"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/pages\/60\/revisions\/62"}],"wp:attachment":[{"href":"https:\/\/graduacao.uel.br\/educacao-fisica\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}